
{"id":12086,"date":"2026-07-22T14:06:23","date_gmt":"2026-07-22T14:06:23","guid":{"rendered":"https:\/\/betatechcenter.com\/?p=12086"},"modified":"2026-07-22T14:14:22","modified_gmt":"2026-07-22T14:14:22","slug":"la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada","status":"publish","type":"post","link":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/","title":{"rendered":"La Generalitat s&#8217;incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[],"expertises":[85,89,90,326,91,247,93,250],"class_list":["post-12086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies","expertises-tecnologies-ambientals-i-bioeconomia-circular","expertises-ecologia-aplicada-i-canvi-global","expertises-sistemes-agraris-alimentaris-sostenibles","expertises-biodiversitat-bioindicadors","expertises-comptabilitat-i-optimitzacio-de-la-sostenibilitat","expertises-transicio-digital-verda","expertises-governanca-per-a-la-sostenibilitat","expertises-transferencia-projectes-territorials-sectorials"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beta Tech Center &#8212; La Generalitat s&#039;incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada<\/title>\n<meta name=\"description\" content=\"La Generalitat de Catalunya s&#039;ha incorporat al Patronat de la Fundaci\u00f3 Centre Tecnol\u00f2gic en Biodiversitat, Ecologia, Tecnologia Ambiental i Aliment\u00e0ria UVic-UCC (Fundaci\u00f3 BETA), consolidant una nova etapa de col\u00b7laboraci\u00f3 institucional per impulsar la recerca aplicada, la innovaci\u00f3 i la transfer\u00e8ncia de coneixement en \u00e0mbits estrat\u00e8gics per al pa\u00eds.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beta Tech Center &#8212; La Generalitat s&#039;incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada\" \/>\n<meta property=\"og:description\" content=\"La Generalitat de Catalunya s&#039;ha incorporat al Patronat de la Fundaci\u00f3 Centre Tecnol\u00f2gic en Biodiversitat, Ecologia, Tecnologia Ambiental i Aliment\u00e0ria UVic-UCC (Fundaci\u00f3 BETA), consolidant una nova etapa de col\u00b7laboraci\u00f3 institucional per impulsar la recerca aplicada, la innovaci\u00f3 i la transfer\u00e8ncia de coneixement en \u00e0mbits estrat\u00e8gics per al pa\u00eds.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/\" \/>\n<meta property=\"og:site_name\" content=\"Beta Tech Center\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-22T14:06:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-22T14:14:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/betatechcenter.com\/wp-content\/uploads\/2021\/03\/AS3I0112-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"beta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"beta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/\"},\"author\":{\"name\":\"beta\",\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/#\\\/schema\\\/person\\\/13e288f068d16eac0192b3bb03a2b410\"},\"headline\":\"La Generalitat s&#8217;incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada\",\"datePublished\":\"2026-07-22T14:06:23+00:00\",\"dateModified\":\"2026-07-22T14:14:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/\"},\"wordCount\":21,\"publisher\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/betatechcenter.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/AS3I0112-scaled.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/\",\"url\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/\",\"name\":\"Beta Tech Center &#8212; La Generalitat s'incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/betatechcenter.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/AS3I0112-scaled.jpg\",\"datePublished\":\"2026-07-22T14:06:23+00:00\",\"dateModified\":\"2026-07-22T14:14:22+00:00\",\"description\":\"La Generalitat de Catalunya s'ha incorporat al Patronat de la Fundaci\u00f3 Centre Tecnol\u00f2gic en Biodiversitat, Ecologia, Tecnologia Ambiental i Aliment\u00e0ria UVic-UCC (Fundaci\u00f3 BETA), consolidant una nova etapa de col\u00b7laboraci\u00f3 institucional per impulsar la recerca aplicada, la innovaci\u00f3 i la transfer\u00e8ncia de coneixement en \u00e0mbits estrat\u00e8gics per al pa\u00eds.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/betatechcenter.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/AS3I0112-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/betatechcenter.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/AS3I0112-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"ct\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/betatechcenter.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Generalitat s&#8217;incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/#website\",\"url\":\"https:\\\/\\\/betatechcenter.com\\\/\",\"name\":\"Beta Tech Center\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/betatechcenter.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/#organization\",\"name\":\"Beta Tech Center\",\"url\":\"https:\\\/\\\/betatechcenter.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/betatechcenter.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/betatechcenter.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo.svg\",\"width\":319,\"height\":88,\"caption\":\"Beta Tech Center\"},\"image\":{\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/betatechcenter.com\\\/#\\\/schema\\\/person\\\/13e288f068d16eac0192b3bb03a2b410\",\"name\":\"beta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b3bf68ae081add1c1a44ae96b02fd1de8189f7f0efe2bd2c025feb66e27ecf79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b3bf68ae081add1c1a44ae96b02fd1de8189f7f0efe2bd2c025feb66e27ecf79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b3bf68ae081add1c1a44ae96b02fd1de8189f7f0efe2bd2c025feb66e27ecf79?s=96&d=mm&r=g\",\"caption\":\"beta\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beta Tech Center &#8212; La Generalitat s'incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada","description":"La Generalitat de Catalunya s'ha incorporat al Patronat de la Fundaci\u00f3 Centre Tecnol\u00f2gic en Biodiversitat, Ecologia, Tecnologia Ambiental i Aliment\u00e0ria UVic-UCC (Fundaci\u00f3 BETA), consolidant una nova etapa de col\u00b7laboraci\u00f3 institucional per impulsar la recerca aplicada, la innovaci\u00f3 i la transfer\u00e8ncia de coneixement en \u00e0mbits estrat\u00e8gics per al pa\u00eds.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/","og_locale":"ca_ES","og_type":"article","og_title":"Beta Tech Center &#8212; La Generalitat s'incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada","og_description":"La Generalitat de Catalunya s'ha incorporat al Patronat de la Fundaci\u00f3 Centre Tecnol\u00f2gic en Biodiversitat, Ecologia, Tecnologia Ambiental i Aliment\u00e0ria UVic-UCC (Fundaci\u00f3 BETA), consolidant una nova etapa de col\u00b7laboraci\u00f3 institucional per impulsar la recerca aplicada, la innovaci\u00f3 i la transfer\u00e8ncia de coneixement en \u00e0mbits estrat\u00e8gics per al pa\u00eds.","og_url":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/","og_site_name":"Beta Tech Center","article_published_time":"2026-07-22T14:06:23+00:00","article_modified_time":"2026-07-22T14:14:22+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/betatechcenter.com\/wp-content\/uploads\/2021\/03\/AS3I0112-scaled.jpg","type":"image\/jpeg"}],"author":"beta","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"beta","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/#article","isPartOf":{"@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/"},"author":{"name":"beta","@id":"https:\/\/betatechcenter.com\/#\/schema\/person\/13e288f068d16eac0192b3bb03a2b410"},"headline":"La Generalitat s&#8217;incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada","datePublished":"2026-07-22T14:06:23+00:00","dateModified":"2026-07-22T14:14:22+00:00","mainEntityOfPage":{"@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/"},"wordCount":21,"publisher":{"@id":"https:\/\/betatechcenter.com\/#organization"},"image":{"@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/#primaryimage"},"thumbnailUrl":"https:\/\/betatechcenter.com\/wp-content\/uploads\/2021\/03\/AS3I0112-scaled.jpg","articleSection":["Not\u00edcies"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/","url":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/","name":"Beta Tech Center &#8212; La Generalitat s'incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada","isPartOf":{"@id":"https:\/\/betatechcenter.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/#primaryimage"},"image":{"@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/#primaryimage"},"thumbnailUrl":"https:\/\/betatechcenter.com\/wp-content\/uploads\/2021\/03\/AS3I0112-scaled.jpg","datePublished":"2026-07-22T14:06:23+00:00","dateModified":"2026-07-22T14:14:22+00:00","description":"La Generalitat de Catalunya s'ha incorporat al Patronat de la Fundaci\u00f3 Centre Tecnol\u00f2gic en Biodiversitat, Ecologia, Tecnologia Ambiental i Aliment\u00e0ria UVic-UCC (Fundaci\u00f3 BETA), consolidant una nova etapa de col\u00b7laboraci\u00f3 institucional per impulsar la recerca aplicada, la innovaci\u00f3 i la transfer\u00e8ncia de coneixement en \u00e0mbits estrat\u00e8gics per al pa\u00eds.","breadcrumb":{"@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/#primaryimage","url":"https:\/\/betatechcenter.com\/wp-content\/uploads\/2021\/03\/AS3I0112-scaled.jpg","contentUrl":"https:\/\/betatechcenter.com\/wp-content\/uploads\/2021\/03\/AS3I0112-scaled.jpg","width":2560,"height":1707,"caption":"ct"},{"@type":"BreadcrumbList","@id":"https:\/\/betatechcenter.com\/ca\/la-generalitat-sincorpora-al-patronat-de-la-fundacio-beta-i-reforca-el-seu-compromis-amb-la-recerca-aplicada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/betatechcenter.com\/ca\/"},{"@type":"ListItem","position":2,"name":"La Generalitat s&#8217;incorpora al Patronat de la Fundaci\u00f3 BETA i refor\u00e7a el seu comprom\u00eds amb la recerca aplicada"}]},{"@type":"WebSite","@id":"https:\/\/betatechcenter.com\/#website","url":"https:\/\/betatechcenter.com\/","name":"Beta Tech Center","description":"","publisher":{"@id":"https:\/\/betatechcenter.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/betatechcenter.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/betatechcenter.com\/#organization","name":"Beta Tech Center","url":"https:\/\/betatechcenter.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/betatechcenter.com\/#\/schema\/logo\/image\/","url":"https:\/\/betatechcenter.com\/wp-content\/uploads\/2020\/12\/logo.svg","contentUrl":"https:\/\/betatechcenter.com\/wp-content\/uploads\/2020\/12\/logo.svg","width":319,"height":88,"caption":"Beta Tech Center"},"image":{"@id":"https:\/\/betatechcenter.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/betatechcenter.com\/#\/schema\/person\/13e288f068d16eac0192b3bb03a2b410","name":"beta","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/b3bf68ae081add1c1a44ae96b02fd1de8189f7f0efe2bd2c025feb66e27ecf79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b3bf68ae081add1c1a44ae96b02fd1de8189f7f0efe2bd2c025feb66e27ecf79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b3bf68ae081add1c1a44ae96b02fd1de8189f7f0efe2bd2c025feb66e27ecf79?s=96&d=mm&r=g","caption":"beta"}}]}},"_links":{"self":[{"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/posts\/12086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/comments?post=12086"}],"version-history":[{"count":3,"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/posts\/12086\/revisions"}],"predecessor-version":[{"id":12095,"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/posts\/12086\/revisions\/12095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/media\/1418"}],"wp:attachment":[{"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/media?parent=12086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/categories?post=12086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/tags?post=12086"},{"taxonomy":"expertises","embeddable":true,"href":"https:\/\/betatechcenter.com\/ca\/wp-json\/wp\/v2\/expertises?post=12086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}